{"id":6267,"date":"2024-05-08T15:00:14","date_gmt":"2024-05-08T20:00:14","guid":{"rendered":"https:\/\/usml.edu\/staff\/sandi-seidl-2\/"},"modified":"2024-05-08T15:45:41","modified_gmt":"2024-05-08T20:45:41","slug":"sandi-seidl-2","status":"publish","type":"staff","link":"https:\/\/usml.edu\/es\/staff\/sandi-seidl-2\/","title":{"rendered":"Sandi Seidl"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Manager, Annual Giving and Alumni Relations<\/p>","protected":false},"author":2,"featured_media":6372,"template":"","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"directory":[24],"class_list":["post-6267","staff","type-staff","status-publish","has-post-thumbnail","hentry","directory-staff"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sandi Seidl - USML<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/usml.edu\/es\/staff\/sandi-seidl-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sandi Seidl - USML\" \/>\n<meta property=\"og:description\" content=\"Manager, Annual Giving and Alumni Relations\" \/>\n<meta property=\"og:url\" content=\"https:\/\/usml.edu\/es\/staff\/sandi-seidl-2\/\" \/>\n<meta property=\"og:site_name\" content=\"USML\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UniversityofSaintMaryoftheLake\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T20:45:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/usml.edu\/wp-content\/uploads\/USML-812-Seidl-Sandra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"944\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MundeleinSem\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/usml.edu\\\/staff\\\/sandi-seidl-2\\\/\",\"url\":\"https:\\\/\\\/usml.edu\\\/staff\\\/sandi-seidl-2\\\/\",\"name\":\"Sandi Seidl - USML\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/usml.edu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/usml.edu\\\/staff\\\/sandi-seidl-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/usml.edu\\\/staff\\\/sandi-seidl-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/usml.edu\\\/wp-content\\\/uploads\\\/USML-812-Seidl-Sandra.jpg\",\"datePublished\":\"2024-05-08T20:00:14+00:00\",\"dateModified\":\"2024-05-08T20:45:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/usml.edu\\\/staff\\\/sandi-seidl-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/usml.edu\\\/staff\\\/sandi-seidl-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/usml.edu\\\/staff\\\/sandi-seidl-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/usml.edu\\\/wp-content\\\/uploads\\\/USML-812-Seidl-Sandra.jpg\",\"contentUrl\":\"https:\\\/\\\/usml.edu\\\/wp-content\\\/uploads\\\/USML-812-Seidl-Sandra.jpg\",\"width\":944,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/usml.edu\\\/staff\\\/sandi-seidl-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/usml.edu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sandi Seidl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/usml.edu\\\/#website\",\"url\":\"https:\\\/\\\/usml.edu\\\/\",\"name\":\"University of Saint Mary of the Lake\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/usml.edu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/usml.edu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/usml.edu\\\/#organization\",\"name\":\"University of Saint Mary of the Lake\",\"url\":\"https:\\\/\\\/usml.edu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/usml.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"University of Saint Mary of the Lake\"},\"image\":{\"@id\":\"https:\\\/\\\/usml.edu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UniversityofSaintMaryoftheLake\",\"https:\\\/\\\/x.com\\\/MundeleinSem\",\"https:\\\/\\\/www.instagram.com\\\/mundeleinsem\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MundeleinSeminary\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sandi Seidl - USML","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/usml.edu\/es\/staff\/sandi-seidl-2\/","og_locale":"es_MX","og_type":"article","og_title":"Sandi Seidl - USML","og_description":"Manager, Annual Giving and Alumni Relations","og_url":"https:\/\/usml.edu\/es\/staff\/sandi-seidl-2\/","og_site_name":"USML","article_publisher":"https:\/\/www.facebook.com\/UniversityofSaintMaryoftheLake","article_modified_time":"2024-05-08T20:45:41+00:00","og_image":[{"width":944,"height":628,"url":"https:\/\/usml.edu\/wp-content\/uploads\/USML-812-Seidl-Sandra.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@MundeleinSem","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/usml.edu\/staff\/sandi-seidl-2\/","url":"https:\/\/usml.edu\/staff\/sandi-seidl-2\/","name":"Sandi Seidl - USML","isPartOf":{"@id":"https:\/\/usml.edu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/usml.edu\/staff\/sandi-seidl-2\/#primaryimage"},"image":{"@id":"https:\/\/usml.edu\/staff\/sandi-seidl-2\/#primaryimage"},"thumbnailUrl":"https:\/\/usml.edu\/wp-content\/uploads\/USML-812-Seidl-Sandra.jpg","datePublished":"2024-05-08T20:00:14+00:00","dateModified":"2024-05-08T20:45:41+00:00","breadcrumb":{"@id":"https:\/\/usml.edu\/staff\/sandi-seidl-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/usml.edu\/staff\/sandi-seidl-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/usml.edu\/staff\/sandi-seidl-2\/#primaryimage","url":"https:\/\/usml.edu\/wp-content\/uploads\/USML-812-Seidl-Sandra.jpg","contentUrl":"https:\/\/usml.edu\/wp-content\/uploads\/USML-812-Seidl-Sandra.jpg","width":944,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/usml.edu\/staff\/sandi-seidl-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/usml.edu\/"},{"@type":"ListItem","position":2,"name":"Sandi Seidl"}]},{"@type":"WebSite","@id":"https:\/\/usml.edu\/#website","url":"https:\/\/usml.edu\/","name":"Universidad de Santa Mar\u00eda del Lago","description":"","publisher":{"@id":"https:\/\/usml.edu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/usml.edu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/usml.edu\/#organization","name":"Universidad de Santa Mar\u00eda del Lago","url":"https:\/\/usml.edu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/usml.edu\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"University of Saint Mary of the Lake"},"image":{"@id":"https:\/\/usml.edu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UniversityofSaintMaryoftheLake","https:\/\/x.com\/MundeleinSem","https:\/\/www.instagram.com\/mundeleinsem\/","https:\/\/www.youtube.com\/user\/MundeleinSeminary"]}]}},"taxonomy_info":{"directory":[{"value":24,"label":"Staff"}]},"featured_image_src_large":["https:\/\/usml.edu\/wp-content\/uploads\/USML-812-Seidl-Sandra.jpg",944,628,false],"author_info":{"display_name":"Ben","author_link":"https:\/\/usml.edu\/es\/author\/benfiatinsight-com\/"},"comment_info":"","publishpress_future_action":{"enabled":false,"date":"2026-07-22 01:13:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"directory","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/usml.edu\/es\/wp-json\/wp\/v2\/staff\/6267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usml.edu\/es\/wp-json\/wp\/v2\/staff"}],"about":[{"href":"https:\/\/usml.edu\/es\/wp-json\/wp\/v2\/types\/staff"}],"author":[{"embeddable":true,"href":"https:\/\/usml.edu\/es\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/usml.edu\/es\/wp-json\/wp\/v2\/media\/6372"}],"wp:attachment":[{"href":"https:\/\/usml.edu\/es\/wp-json\/wp\/v2\/media?parent=6267"}],"wp:term":[{"taxonomy":"directory","embeddable":true,"href":"https:\/\/usml.edu\/es\/wp-json\/wp\/v2\/directory?post=6267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}